{"id":958,"date":"2014-12-30T14:58:25","date_gmt":"2014-12-30T14:58:25","guid":{"rendered":"https:\/\/www.nesc.ie\/?post_type=publications&#038;p=958"},"modified":"2026-04-14T13:09:24","modified_gmt":"2026-04-14T12:09:24","slug":"national-economic-and-social-development-office-annual-report-2013","status":"publish","type":"publications","link":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/","title":{"rendered":"National Economic and Social Development Office Annual Report 2013"},"content":{"rendered":"","protected":false},"author":1,"featured_media":9334,"template":"","publication_type":[82],"research_area":[],"class_list":["post-958","publications","type-publications","status-publish","has-post-thumbnail","hentry","publication_type-nesdo-annual-reports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/\" \/>\n<meta property=\"og:site_name\" content=\"National Economic &amp; Social Council\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T12:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/\",\"url\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/\",\"name\":\"National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nesc.ie\\\/app\\\/uploads\\\/2026\\\/04\\\/NESDO_-e1776167247332.jpg\",\"datePublished\":\"2014-12-30T14:58:25+00:00\",\"dateModified\":\"2026-04-14T12:09:24+00:00\",\"inLanguage\":\"ga\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ga\",\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/publications\\\/national-economic-and-social-development-office-annual-report-2013\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.nesc.ie\\\/app\\\/uploads\\\/2026\\\/04\\\/NESDO_-e1776167247332.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nesc.ie\\\/app\\\/uploads\\\/2026\\\/04\\\/NESDO_-e1776167247332.jpg\",\"width\":870,\"height\":890},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/#website\",\"url\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/\",\"name\":\"National Economic &amp; Social Council\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nesc.ie\\\/ga\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ga\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/","og_locale":"en_US","og_type":"article","og_title":"National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council","og_url":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/","og_site_name":"National Economic &amp; Social Council","article_modified_time":"2026-04-14T12:09:24+00:00","og_image":[{"width":870,"height":890,"url":"https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/","url":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/","name":"National Economic and Social Development Office Annual Report 2013 - National Economic &amp; Social Council","isPartOf":{"@id":"https:\/\/www.nesc.ie\/ga\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/#primaryimage"},"image":{"@id":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/#primaryimage"},"thumbnailUrl":"https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg","datePublished":"2014-12-30T14:58:25+00:00","dateModified":"2026-04-14T12:09:24+00:00","inLanguage":"ga","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/"]}]},{"@type":"ImageObject","inLanguage":"ga","@id":"https:\/\/www.nesc.ie\/ga\/publications\/national-economic-and-social-development-office-annual-report-2013\/#primaryimage","url":"https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg","contentUrl":"https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg","width":870,"height":890},{"@type":"WebSite","@id":"https:\/\/www.nesc.ie\/ga\/#website","url":"https:\/\/www.nesc.ie\/ga\/","name":"National Economic &amp; Social Council","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nesc.ie\/ga\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ga"}]}},"spectra_custom_meta":{"_edit_lock":["1776168566:2"],"_edit_last":["2","2"],"_yoast_wpseo_primary_publication_type":["82","82"],"_yoast_wpseo_primary_publication_topic":["",""],"_yoast_wpseo_content_score":["90","90"],"noOfUrls":["2","2"],"fileUrl0":["http:\/\/files.nesc.ie\/nesdo_documents\/2013_English_no appendix.pdf","http:\/\/files.nesc.ie\/nesdo_documents\/2013_English_no appendix.pdf"],"fileSize0":["1.34 MB","1.34 MB"],"fileUrl1":["http:\/\/files.nesc.ie\/nesdo_documents\/2013_NESDO_ Annual_Report_GA.pdf","http:\/\/files.nesc.ie\/nesdo_documents\/2013_NESDO_ Annual_Report_GA.pdf"],"fileTitle1":["National Economic and Social Development Office Annual Report 2013 (Irish Version)","National Economic and Social Development Office Annual Report 2013 (Irish Version)"],"fileSize1":["740.24 kB","740.24 kB"],"report_number":["7","7"],"_report_number":["field_5b744516d862f","field_5b744516d862f"],"classic-editor-remember":["block-editor"],"_thumbnail_id":["9334"],"copied_media_ids":["a:0:{}"],"referenced_media_ids":["a:1:{i:0;i:9334;}"],"_wpml_word_count":["11"],"permitted_users":[""],"_permitted_users":["field_5b4722db60858"],"related_publications":[""],"_related_publications":["field_5c1a433464528"],"related_news_events":[""],"_related_news_events":["field_5c1a44096452a"],"related_work_programme":[""],"_related_work_programme":["field_5c34e3709695b"],"show_related_work_programme":["0"],"_show_related_work_programme":["field_5c417472bc016"],"_yoast_wpseo_primary_research_area":[""],"_yoast_wpseo_primary_work_programme":[""],"_yoast_wpseo_estimated-reading-time-minutes":["0"],"_uag_page_assets":["a:9:{s:3:\"css\";s:27527:\".wp-block-uagb-container.uagb-block-8d8cc136.wp-block-uagb-container{color: #ffffff;}.wp-block-uagb-container.uagb-block-8d8cc136.wp-block-uagb-container *{color: #ffffff;}.wp-block-uagb-container.uagb-block-8d8cc136 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d8cc136 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d8cc136 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-8d8cc136 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-8d8cc136 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d8cc136{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d8cc136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1101px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-8d8cc136{box-shadow: 0px 0px   #00000070 ;padding-top: 40px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 1%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/www.nesc.ie\/app\/uploads\/2026\/03\/footer-bg.jpg);background-clip: padding-box;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d8cc136{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d8cc136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-8d8cc136{padding-top: 40px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.nesc.ie\/app\/uploads\/2026\/03\/footer-bg.jpg);background-clip: padding-box;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-8d8cc136{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-8d8cc136 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-8d8cc136{padding-top: 40px;padding-bottom: 40px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/www.nesc.ie\/app\/uploads\/2026\/03\/footer-bg.jpg);background-clip: padding-box;}}.wp-block-uagb-container.uagb-block-e266560b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e266560b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e266560b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e266560b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e266560b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e266560b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e266560b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1100px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e266560b{min-height: 100px;box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 100px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: inherit;background-color: #f7f8fd;;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e266560b::before{content: \"\";position: absolute;pointer-events: none;top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: inherit;background-repeat: no-repeat;background-position: 80% 30px;background-size: 300px;background-attachment: scroll;mix-blend-mode: multiply;background-clip: padding-box;opacity: 1;}.wp-block-uagb-container.uagb-block-e266560b.uag-blocks-common-selector{--z-index-desktop: 10;}.wp-block-uagb-container.uagb-block-efe36411 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-efe36411 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-efe36411 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-efe36411 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-efe36411 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efe36411{max-width: 863px;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efe36411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-efe36411{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b4d6b2b1 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4d6b2b1 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4d6b2b1 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-b4d6b2b1 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-b4d6b2b1 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4d6b2b1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4d6b2b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-b4d6b2b1{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-advanced-heading.uagb-block-b0923400.wp-block-uagb-advanced-heading .uagb-heading-text{color: #001e3c;}.wp-block-uagb-advanced-heading.uagb-block-b0923400.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-b0923400.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b0923400.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b0923400.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-b0923400 .uagb-heading-text{font-family: \"Figtree\";font-weight: 900;font-size: 48px;}.wp-block-uagb-container.uagb-block-9a45c662 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a45c662 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a45c662 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9a45c662 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9a45c662 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a45c662{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a45c662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9a45c662{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-9a45c662.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-9a45c662.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading .uagb-heading-text{color: #000;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading {background: #dde5f0;padding-top: 10px;padding-right: 15px;padding-bottom: 10px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7f737b2c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6725db8d.wp-block-uagb-advanced-heading {background: #dde5f0;padding-top: 10px;padding-right: 15px;padding-bottom: 10px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6725db8d.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6725db8d.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;border-top-left-radius: 20px;border-top-right-radius: 20px;border-bottom-left-radius: 20px;border-bottom-right-radius: 20px;}.wp-block-uagb-advanced-heading.uagb-block-6725db8d.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6725db8d.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8041ccc0.wp-block-uagb-advanced-heading {background: #dde5f0;padding-top: 10px;padding-right: 15px;padding-bottom: 10px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8041ccc0.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-8041ccc0.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #dde5f0;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8041ccc0.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #dde5f0;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-8041ccc0.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #dde5f0;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5040dd82.wp-block-uagb-advanced-heading {background: #dde5f0;padding-top: 10px;padding-right: 15px;padding-bottom: 10px;padding-left: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5040dd82.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-5040dd82.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5040dd82.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-5040dd82.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-container.uagb-block-2eb847ec .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2eb847ec .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2eb847ec .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-2eb847ec .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-2eb847ec .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eb847ec{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eb847ec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-2eb847ec{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 14px;padding-right: 14px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-0dbfb41f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0dbfb41f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0dbfb41f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0dbfb41f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0dbfb41f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0dbfb41f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0dbfb41f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 10px;column-gap: 15px;}.wp-block-uagb-container.uagb-block-0dbfb41f{box-shadow: 0px 18px 40px -10px rgba(0,0,0,0.2) ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -60px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-color: inherit;background-color: #ffffff;;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 10px;column-gap: 15px;}.wp-block-uagb-container.uagb-block-e13891bc .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e13891bc .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e13891bc .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e13891bc .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e13891bc .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e13891bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e13891bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1340px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}.wp-block-uagb-container.uagb-block-e13891bc{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e266560b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e266560b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e266560b{padding-top: 30px;padding-bottom: 100px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f7f8fd;;}.wp-block-uagb-container.uagb-block-e266560b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);mix-blend-mode: multiply;background-clip: padding-box;opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efe36411{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efe36411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-efe36411{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4d6b2b1{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4d6b2b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-b4d6b2b1{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a45c662{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a45c662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9a45c662{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eb847ec{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eb847ec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-2eb847ec{padding-top: 10px;padding-bottom: 10px;padding-left: 14px;padding-right: 14px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0dbfb41f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0dbfb41f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-0dbfb41f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -60px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #ffffff;;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e13891bc{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e13891bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e13891bc{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e266560b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e266560b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e266560b{padding-top: 30px;padding-bottom: 100px;padding-left: 10px;padding-right: 10px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f7f8fd;;}.wp-block-uagb-container.uagb-block-e266560b::before{top: -0px;left: -0px;width: calc(100% + 0px + 0px);height: calc(100% + 0px + 0px);mix-blend-mode: multiply;background-clip: padding-box;opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-efe36411{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-efe36411 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-efe36411{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-b4d6b2b1{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-b4d6b2b1 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-b4d6b2b1{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9a45c662{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9a45c662 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9a45c662{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-2eb847ec{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-2eb847ec > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-2eb847ec{padding-top: 10px;padding-bottom: 10px;padding-left: 14px;padding-right: 14px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0dbfb41f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0dbfb41f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0dbfb41f{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: -60px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #ffffff;;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e13891bc{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e13891bc > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e13891bc{padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:12:{i:0;s:11:\"nesc\/header\";i:1;s:14:\"uagb\/container\";i:4;s:21:\"uagb\/advanced-heading\";i:6;s:33:\"fusio\/nesc-publications-downloads\";i:9;s:17:\"core\/post-content\";i:11;s:12:\"core\/columns\";i:12;s:11:\"core\/column\";i:13;s:12:\"core\/heading\";i:16;s:10:\"core\/image\";i:17;s:14:\"core\/paragraph\";i:18;s:15:\"core\/navigation\";i:19;s:10:\"core\/group\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778691629\";s:6:\"gfonts\";a:1:{s:7:\"Figtree\";a:2:{s:10:\"fontfamily\";s:7:\"Figtree\";s:12:\"fontvariants\";a:1:{i:0;s:3:\"900\";}}}s:10:\"gfonts_url\";s:85:\"\/\/fonts.googleapis.com\/css?family=Figtree:900,900italic&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg",870,890,false],"thumbnail":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-150x150.jpg",150,150,true],"medium":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-293x300.jpg",293,300,true],"medium_large":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-768x786.jpg",768,786,true],"large":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-839x1024.jpg",839,1024,true],"1536x1536":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg",870,890,false],"2048x2048":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg",870,890,false],"large_nocrop":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332.jpg",870,890,false],"gform-image-choice-sm":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-300x300.jpg",300,300,true],"gform-image-choice-md":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-400x400.jpg",400,400,true],"gform-image-choice-lg":["https:\/\/www.nesc.ie\/app\/uploads\/2026\/04\/NESDO_-e1776167247332-600x600.jpg",600,600,true]},"uagb_author_info":{"display_name":"fusio","author_link":"https:\/\/www.nesc.ie\/ga\/news-events\/author\/fusio\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/publications\/958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/publications"}],"about":[{"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/types\/publications"}],"author":[{"embeddable":true,"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/media\/9334"}],"wp:attachment":[{"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/media?parent=958"}],"wp:term":[{"taxonomy":"publication_type","embeddable":true,"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/publication_type?post=958"},{"taxonomy":"research_area","embeddable":true,"href":"https:\/\/www.nesc.ie\/ga\/wp-json\/wp\/v2\/research_area?post=958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}